{"id":34,"count":8,"description":"","link":"https:\/\/proandre.com\/en\/product-category\/eliminacion-de-olores\/","name":"Bad Odour Eliminators","slug":"eliminacion-de-olores","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Eliminaci\u00f3n de Olores archivos - Productos de Higiene y Ambientaci\u00f3n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proandre.com\/en\/product-category\/eliminacion-de-olores\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eliminaci\u00f3n de Olores archivos - Productos de Higiene y Ambientaci\u00f3n\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proandre.com\/en\/product-category\/eliminacion-de-olores\/\" \/>\n<meta property=\"og:site_name\" content=\"Productos de Higiene y Ambientaci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/proandre.com\\\/categoria-producto\\\/eliminacion-de-olores\\\/\",\"url\":\"https:\\\/\\\/proandre.com\\\/categoria-producto\\\/eliminacion-de-olores\\\/\",\"name\":\"Eliminaci\u00f3n de Olores archivos - Productos de Higiene y Ambientaci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proandre.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proandre.com\\\/categoria-producto\\\/eliminacion-de-olores\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proandre.com\\\/categoria-producto\\\/eliminacion-de-olores\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/proandre.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eliminaci\u00f3n de Olores\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proandre.com\\\/#website\",\"url\":\"https:\\\/\\\/proandre.com\\\/\",\"name\":\"Proandre\",\"description\":\"Proandre es una empresa espa\u00f1ola con presencia internacional, dedicada a la fabricaci\u00f3n y comercializaci\u00f3n de productos de higiene y ambientaci\u00f3n, as\u00ed como complementos para las empresas de control de plagas\",\"publisher\":{\"@id\":\"https:\\\/\\\/proandre.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proandre.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/proandre.com\\\/#organization\",\"name\":\"Proandre\",\"url\":\"https:\\\/\\\/proandre.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/proandre.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/proandre.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/logo-proandre.png\",\"contentUrl\":\"https:\\\/\\\/proandre.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/logo-proandre.png\",\"width\":640,\"height\":90,\"caption\":\"Proandre\"},\"image\":{\"@id\":\"https:\\\/\\\/proandre.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Eliminaci\u00f3n de Olores archivos - Productos de Higiene y Ambientaci\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proandre.com\/en\/product-category\/eliminacion-de-olores\/","og_locale":"en_GB","og_type":"article","og_title":"Eliminaci\u00f3n de Olores archivos - Productos de Higiene y Ambientaci\u00f3n","og_url":"https:\/\/proandre.com\/en\/product-category\/eliminacion-de-olores\/","og_site_name":"Productos de Higiene y Ambientaci\u00f3n","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/proandre.com\/categoria-producto\/eliminacion-de-olores\/","url":"https:\/\/proandre.com\/categoria-producto\/eliminacion-de-olores\/","name":"Eliminaci\u00f3n de Olores archivos - Productos de Higiene y Ambientaci\u00f3n","isPartOf":{"@id":"https:\/\/proandre.com\/#website"},"breadcrumb":{"@id":"https:\/\/proandre.com\/categoria-producto\/eliminacion-de-olores\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/proandre.com\/categoria-producto\/eliminacion-de-olores\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/proandre.com\/"},{"@type":"ListItem","position":2,"name":"Eliminaci\u00f3n de Olores"}]},{"@type":"WebSite","@id":"https:\/\/proandre.com\/#website","url":"https:\/\/proandre.com\/","name":"Proandre","description":"Proandre es una empresa espa\u00f1ola con presencia internacional, dedicada a la fabricaci\u00f3n y comercializaci\u00f3n de productos de higiene y ambientaci\u00f3n, as\u00ed como complementos para las empresas de control de plagas","publisher":{"@id":"https:\/\/proandre.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proandre.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/proandre.com\/#organization","name":"Proandre","url":"https:\/\/proandre.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/proandre.com\/#\/schema\/logo\/image\/","url":"https:\/\/proandre.com\/wp-content\/uploads\/2025\/05\/logo-proandre.png","contentUrl":"https:\/\/proandre.com\/wp-content\/uploads\/2025\/05\/logo-proandre.png","width":640,"height":90,"caption":"Proandre"},"image":{"@id":"https:\/\/proandre.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/proandre.com\/en\/wp-json\/wp\/v2\/product_cat\/34","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proandre.com\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/proandre.com\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/proandre.com\/en\/wp-json\/wp\/v2\/product?product_cat=34"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}